{"id":25,"count":25,"description":"","link":"https:\/\/www.hiersein.at\/op\/veranstaltungen\/kategorie\/donaldson\/einfuehrungs-workshop\/","name":"Einf\u00fchrungsworkshop","slug":"einfuehrungs-workshop","taxonomy":"tribe_events_cat","parent":23,"meta":[],"_links":{"self":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/tribe_events_cat\/25"}],"collection":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/tribe_events_cat\/23"}],"wp:post_type":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}