{"id":790,"date":"2016-02-14T17:13:59","date_gmt":"2016-02-14T15:13:59","guid":{"rendered":"https:\/\/www.hiersein.at\/op\/?page_id=790"},"modified":"2019-12-10T08:33:01","modified_gmt":"2019-12-10T06:33:01","slug":"lernen","status":"publish","type":"page","link":"https:\/\/www.hiersein.at\/op\/lernen\/","title":{"rendered":"Lernen"},"content":{"rendered":"<div id=\"pl-790\"  class=\"panel-layout\" ><div id=\"pg-790-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-0\" style=\"padding: 0em 0; \" data-stretch-type=\"full-stretched\" data-overlay=\"true\" ><div id=\"pgc-790-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-0-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"so-parallax panel-widget-style panel-widget-style-for-790-0-0-0\" style=\"text-align: left;\" data-title-color=\"#ffffff\" data-headings-color=\"#ffffff\" ><img width=\"1200\" height=\"600\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01.jpg\" class=\"attachment-full size-full\" alt=\"Foto einer Gruppe von Erwachsenen beim Spielen\" decoding=\"async\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01.jpg 1200w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-300x150.jpg 300w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-768x384.jpg 768w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-1024x512.jpg 1024w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-600x300.jpg 600w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-480x240.jpg 480w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-830x415.jpg 830w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-230x115.jpg 230w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-01-350x175.jpg 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-142cd9826658-790\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t<h2 class='sow-headline'>\"Vielen herzlichen Dank f\u00fcr so viel intensive N\u00e4he.\"<\/h2>\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<h5 class='sow-sub-headline'>Workshopteilnehmer<\/h5><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-1\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-1\" style=\"padding: 1em 0; \" data-stretch-type=\"full\" data-overlay=\"true\" ><div id=\"pgc-790-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-1-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #c62a2c;\">Weiterbildungen\u00a0mit Fred Donaldson und Jolanta Graczykowska<\/span><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-2\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-2\" style=\"padding: 0em 0; \" data-stretch-type=\"full\" data-overlay=\"true\" ><div id=\"pgc-790-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-2-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h4 style=\"text-align: center;\">Fred Donaldson<\/h4>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"img-circle aligncenter wp-image-403 size-thumbnail\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2014\/04\/Fred-Donaldson-laedt-ein-e1457793362440-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p style=\"text-align: center;\"><a class=\"footrigger\" href=\"#fred-spielen\">Fotogalerie<br \/><\/a><a href=\"mailto:ofreddybear@aol.com\">ofreddybear@aol.com<\/a><br \/>(in Englisch anschreiben)<\/p>\n<div id=\"fred-spielen\" style=\"display: none;\">[foogallery id=\"1123\"]<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-790-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-790-2-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"3\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-2-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: center;\">\u00a0<\/p>\n<p style=\"text-align: center;\">In Europa sind nur Fred Donaldson und Jolanta Graczykowska autorisiert, Vortr\u00e4ge und Workshops in\u00a0Original Play abzuhalten.<\/p>\n<p style=\"text-align: center;\">Sie bieten international Vortr\u00e4ge, Workshops, Seminare, Praxistage und Spieleinheiten mit Kindern und Beratung an.<\/p>\n<p style=\"text-align: center;\">Alle Workshop- und Seminartermine in Europa finden Sie unter:<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-887\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/03\/original-play-eu-klein.png\" alt=\"Logo von Original Play Europa\" width=\"80\" height=\"80\" \/><br \/><a href=\"https:\/\/originalplay.eu\" target=\"_blank\" rel=\"noopener\">www.originalplay.eu<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-790-2-2\"  class=\"panel-grid-cell\" ><div id=\"panel-790-2-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"4\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-2-2-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h4 style=\"text-align: center;\">Jolanta Graczykowska<\/h4>\n<p style=\"text-align: right;\"><img decoding=\"async\" loading=\"lazy\" class=\"img-circle wp-image-797 size-thumbnail aligncenter\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/jolanta_graczykowska-e1457793267575-150x150.jpeg\" alt=\"jolanta_graczykowska\" width=\"150\" height=\"150\" \/><\/p>\n<p style=\"text-align: center;\"><a class=\"footrigger\" href=\"#jola-spielen\">Fotogalerie<br \/><\/a><a href=\"mailto:jola@originalplay.eu\">jola@originalplay.eu<\/a><br \/>(in Englisch anschreiben)<\/p>\n<div id=\"jola-spielen\" style=\"display: none;\">[foogallery id=\"1104\"]<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-3\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-3\" style=\"padding: 2em 0; \" data-stretch-type=\"full\" data-overlay=\"true\" ><div id=\"pgc-790-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-3-0-0\" class=\"so-panel widget widget_sow-features panel-first-child panel-last-child\" data-index=\"5\" ><div class=\"wow zoomInUp panel-widget-style panel-widget-style-for-790-3-0-0\" style=\"text-align: left;\" data-wow-offset=\"10\" data-wow-iteration=\"1\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-features so-widget-sow-features-default-f28d6caa45b1-790\"\n\t\t\t\n\t\t>\n<div class=\"sow-features-list sow-features-responsive\">\n\n\t\t\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\"\n\t\t\t\tstyle=\"display: flex; flex-direction: column; float: left; width: 33.333%;\"\n\t\t\t>\n\t\t\t\t\t\t\t<div class=\"sow-features-feature-right-left-container\" style=\"display: flex; flex-direction: inherit;\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/vortrag\/\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-round\"\n\t\t\t\t\tstyle=\"color: #ffd300; \"\n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf2d8;\"\n\t\tstyle=\"font-size: 60px; color: #ffffff\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"sow-features-feature-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/vortrag\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tVortr\u00e4ge\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p>Fred Donaldson schildert, wie er Original Play durch das Spielen mit kleinen Kindern entdeckt hat. Auf ber\u00fchrende Weise erz\u00e4hlt er von seinen vielf\u00e4ltigen Spielerfahrungen mit Kindern, Menschen in besonderen Lebenssituationen und freilebenden Tieren. Mittels Fotos und Filmen zeigt er den Anwesenden, wie er mit Kindern, Jugendlichen und W\u00f6lfen spielt. Er beantwortet auch gerne Fragen aus dem Publikum. Der Vortrag findet in englischer Sprache mit deutscher \u00dcbersetzung statt.<\/p>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p class=\"sow-more-text\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/vortrag\/\" >\t\t\t\t\t\t\tTermine\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\"\n\t\t\t\tstyle=\"display: flex; flex-direction: column; float: left; width: 33.333%;\"\n\t\t\t>\n\t\t\t\t\t\t\t<div class=\"sow-features-feature-right-left-container\" style=\"display: flex; flex-direction: inherit;\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/einfuehrungs-workshop\/\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-round\"\n\t\t\t\t\tstyle=\"color: #ffd300; \"\n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf2d9;\"\n\t\tstyle=\"font-size: 60px; color: #ffffff\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"sow-features-feature-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/einfuehrungs-workshop\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tEinf\u00fchrungsworkshops\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p>Fred Donaldson f\u00fchrt mit vielen \u00dcbungen behutsam in die Haltung und Erfahrung von Original Play ein. Dabei macht er k\u00f6rperlich erfahrbar, wie unterschiedlich sich Wettbewerbs- bzw Spielhaltung anf\u00fchlen. So lernen die Teilnehmer*innen zum einen, sich f\u00fcr das Spiel mit Kindern zu \u00f6ffnen, und bekommen dar\u00fcber hinaus eine Ahnung, wie Original Play Aggression und Gewalt verwandeln und ihr Leben zu mehr Pr\u00e4senz und freundlicher G\u00fcte f\u00fchren kann.<\/p>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p class=\"sow-more-text\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/einfuehrungs-workshop\/\" >\t\t\t\t\t\t\tTermine\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\"\n\t\t\t\tstyle=\"display: flex; flex-direction: column; float: left; width: 33.333%;\"\n\t\t\t>\n\t\t\t\t\t\t\t<div class=\"sow-features-feature-right-left-container\" style=\"display: flex; flex-direction: inherit;\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/vertiefungs-workshop\/\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-round\"\n\t\t\t\t\tstyle=\"color: #ffd300; \"\n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf2d9;\"\n\t\tstyle=\"font-size: 60px; color: #ffffff\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"sow-features-feature-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/vertiefungs-workshop\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tVertiefungsworkshops\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p>Vertiefungsworkshops richten sich an alle Menschen, die schon einen Einf\u00fchrungsworkshop besucht haben. Im Workshop geht es um weitere vertiefende K\u00f6rper\u00fcbungen und darum, was wir als Spielleiter*innen tun k\u00f6nnen, wenn eingeladene Spielende uns bei\u00dfen, treten, schlagen, an den Haaren rei\u00dfen, ... und wie wir dennoch in unserer liebevollen Spielenergie bleiben und alle Menschen auf und abseits der Spielfl\u00e4che sicher halten.<\/p>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p class=\"sow-more-text\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hiersein.at\/op\/veranstaltungen\/category\/vertiefungs-workshop\/\" >\t\t\t\t\t\t\tTermine\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-4\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-4\" style=\"padding: 1em 0; \" data-stretch-type=\"full-stretched\" data-overlay=\"true\" ><div id=\"pgc-790-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-4-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"6\" ><div class=\"so-parallax panel-widget-style panel-widget-style-for-790-4-0-0\" style=\"text-align: left;\" data-title-color=\"#ffffff\" data-headings-color=\"#ffffff\" ><img width=\"1200\" height=\"600\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05.jpg\" class=\"attachment-full size-full\" alt=\"Foto: Fred und Sonja spielen\" decoding=\"async\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05.jpg 1200w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-300x150.jpg 300w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-768x384.jpg 768w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-1024x512.jpg 1024w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-600x300.jpg 600w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-480x240.jpg 480w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-830x415.jpg 830w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-230x115.jpg 230w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-05-350x175.jpg 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-142cd9826658-790\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t<h2 class='sow-headline'>\"Das war das spannendste Wochenende in meinem Leben, Danke!\"<\/h2>\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<h5 class='sow-sub-headline'>Workshopteilnehmerin<\/h5><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-5\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-5\" style=\"padding: 1em 0; \" data-stretch-type=\"full\" data-overlay=\"true\" ><div id=\"pgc-790-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-5-0-0\" class=\"so-panel widget widget_sow-features panel-first-child panel-last-child\" data-index=\"7\" ><div class=\"wow zoomInUp panel-widget-style panel-widget-style-for-790-5-0-0\" style=\"text-align: left;\" data-wow-offset=\"10\" data-wow-iteration=\"1\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-features so-widget-sow-features-default-67344d5beee1-790\"\n\t\t\t\n\t\t>\n<div class=\"sow-features-list sow-features-responsive\">\n\n\t\t\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\"\n\t\t\t\tstyle=\"display: flex; flex-direction: column; float: left; width: 50%;\"\n\t\t\t>\n\t\t\t\t\t\t\t<div class=\"sow-features-feature-right-left-container\" style=\"display: flex; flex-direction: inherit;\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"https:\/\/originalplay.eu\/events\/category\/b-event-type\/international-training-seminars\/\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-round\"\n\t\t\t\t\tstyle=\"color: #ffd300; \"\n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf2d9;\"\n\t\tstyle=\"font-size: 60px; color: #ffffff\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"sow-features-feature-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/originalplay.eu\/events\/category\/b-event-type\/international-training-seminars\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tSeminare\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p><span class=\"s1\">Vorraussetzungen f\u00fcr das Basic Training Seminar sind die Teilnahme an mindestens einem Workshop<\/span><span class=\"s1\">. Das Seminar verfolgt zwei Ziele: Die Vermittlung begleiteter <\/span><span class=\"s1\">Spielerfahrungen mit einer Vielzahl von Kindern in unterschiedlichsten Kontexten und\u00a0<\/span><span class=\"s1\">die Erm\u00f6glichung eines Kennenlernens und Erfahrungsaustausches mit Menschen aus ganz\u00a0Europa,\u00a0<\/span><span class=\"s1\">die an Original Play interessiert sind, um den Grundstein zuk\u00fcnftiger Kooperationen legen zu k\u00f6nnen.<\/span><\/p>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p class=\"sow-more-text\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/originalplay.eu\/events\/category\/b-event-type\/international-training-seminars\/\" >\t\t\t\t\t\t\tTermine\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"sow-features-feature sow-icon-container-position-top sow-features-feature-last-row\"\n\t\t\t\tstyle=\"display: flex; flex-direction: column; float: left; width: 50%;\"\n\t\t\t>\n\t\t\t\t\t\t\t<div class=\"sow-features-feature-right-left-container\" style=\"display: flex; flex-direction: inherit;\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"mailto:jola@originalplay.pl\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"sow-icon-container sow-container-round\"\n\t\t\t\t\tstyle=\"color: #ffd300; \"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t<div class=\"textwidget\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"sow-features-feature-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\thref=\"mailto:jola@originalplay.pl\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tShadowplay\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p>Shadowplay ist ein exklusives Angebot von Jolanta Graczykowska. Es wird ein individueller Zeitrahmen vereinbart, zu dem einzelne Erwachsene, die schon mindestens ein Basic Training Seminar besucht haben, Jolanta Graczykowska in Warschau beim Spielen in verschiedene Kinderg\u00e4rten, Schulen und Einrichtungen f\u00fcr Menschen mit Behinderungen begleiten. Die sprachliche Verst\u00e4ndigung findet auf Englisch statt. Bei Interesse wende dich bitte direkt an Jola per E-mail (in Englisch).<\/p>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p class=\"sow-more-text\">\n\t\t\t\t\t\t\t<a href=\"mailto:jola@originalplay.pl\" >\t\t\t\t\t\t\tKontakt\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-6\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-6\" style=\"padding: 1em 0; \" data-stretch-type=\"full-stretched\" data-overlay=\"true\" ><div id=\"pgc-790-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-6-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"8\" ><div class=\"so-parallax panel-widget-style panel-widget-style-for-790-6-0-0\" style=\"text-align: left;\" data-title-color=\"#ffffff\" data-headings-color=\"#ffffff\" ><img width=\"1200\" height=\"600\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04.jpg\" class=\"attachment-full size-full\" alt=\"Foto einer Gruppe von Kindern und Erwachsenen, die spielen\" decoding=\"async\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04.jpg 1200w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-300x150.jpg 300w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-768x384.jpg 768w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-1024x512.jpg 1024w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-600x300.jpg 600w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-480x240.jpg 480w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-830x415.jpg 830w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-230x115.jpg 230w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-04-350x175.jpg 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-142cd9826658-790\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t<h2 class='sow-headline'>\"Der Workshop ist ein Mix aus lebendiger Theorie und Praxis. Original Play ist sehr viel mehr, als ich erwartet habe.\"<\/h2>\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<h5 class='sow-sub-headline'>Workshopteilnehmerin<\/h5><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-7\"  class=\"panel-grid panel-has-style\" ><div style=\"padding: 2em 0; \" data-overlay=\"true\" class=\"panel-row-style panel-row-style-for-790-7\" ><div id=\"pgc-790-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-7-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"9\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-7-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #c62a2c;\">Leitfaden f\u00fcr eine Lehrzeit in Original Play<\/span><\/h2>\n<h4 style=\"text-align: center;\">von Fred Donaldson<\/h4>\n<p class=\"p1\">\u00a0<\/p>\n<p class=\"p3\"><span class=\"s1\">Diese Orientierungshilfe ist vor allem f\u00fcr diejenigen geschrieben, die sich, nachdem sie an Workshops f\u00fcr Original Play teilgenommen haben und begonnen haben mit Kindern zu spielen, dazu entscheiden, dass sie das Urspr\u00fcngliche Spiel mit gr\u00f6\u00dferer Ernsthaftigkeit weiterverfolgen wollen.<\/span><\/p>\n<p class=\"p3\"><span class=\"s1\">Die folgenden Leitlinien wurden aus sechs Gr\u00fcnden erstellt:<\/span><\/p>\n<ol>\n<li class=\"p3\"><span class=\"s1\">Manchmal m\u00f6chten Menschen von uns empfohlen werden.<\/span><\/li>\n<li class=\"p3\"><span class=\"s1\">Manchmal sind Menschen der Meinung, dass sie Original Play \u201eunterrichten\u201c oder andere in ihrem Spiel mit Kindern \u201eanleiten\u201c k\u00f6nnten, nachdem sie einige Workshops besucht haben.<\/span><\/li>\n<li class=\"p3\"><span class=\"s1\">Um die Aufmerksamkeit interessierter Teilnehmer*innen auf die Notwendigkeit zu lenken, Original Play von Kindern zu lernen, ist es unabdingbar f\u00fcr jede*n Einzelne*n<\/span><span class=\"s1\">, die*der im Original Play weiter wachsen will, ein klares Verst\u00e4ndnis f\u00fcr die Integrit\u00e4t und Verantwortung zu haben, die mit dieser Wahl verbunden sind.<\/span><\/li>\n<li class=\"p3\"><span class=\"s1\">Es ist wichtig einige Leitlinien vorzulegen, um eine Idee davon zu vermitteln, welche Breite und Tiefe der Verpflichtung dem Original Play gegen\u00fcber erforderlich ist, damit jemand<\/span><\/li>\n<li class=\"p3\"><span class=\"s1\">sich mit anderen Menschen, die spielen, verbinden und diese unterst\u00fctzen kann.<\/span><\/li>\n<li class=\"p3\"><span class=\"s1\">lernen kann, wie man sich selbst wirkungsvoll in der \u00d6ffentlichkeit darstellt.<\/span><\/li>\n<\/ol>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-8\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-8\" style=\"padding: 1em 0; \" data-stretch-type=\"full-stretched\" data-overlay=\"true\" ><div id=\"pgc-790-8-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-8-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"10\" ><div class=\"so-parallax panel-widget-style panel-widget-style-for-790-8-0-0\" style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" ><img width=\"1200\" height=\"600\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07.jpg\" class=\"attachment-full size-full\" alt=\"Foto von einem Vortrag mit Fred Donaldson\" decoding=\"async\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07.jpg 1200w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-300x150.jpg 300w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-768x384.jpg 768w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-1024x512.jpg 1024w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-600x300.jpg 600w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-480x240.jpg 480w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-830x415.jpg 830w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-230x115.jpg 230w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-07-350x175.jpg 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #fff;\">Die Leute fragen mich h\u00e4ufig:<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #fff;\"> \u201cWann kann ich Original Play unterrichten?\u201d<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #fff;\">Das ist die falsche Frage.<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #fff;\">Je mehr ich spiele, desto mehr verstehe ich, dass ich immer weniger wei\u00df.<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #fff;\">Die entscheidende Frage lautet also stattdessen:<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #fff;\"> \u201cWie kann ich immer mehr \u00fcber Original Play lernen?\"<\/span><\/h2>\n<h6 style=\"text-align: center;\"><span style=\"color: #fff;\"> Fred Donaldson<\/span><\/h6>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-9\"  class=\"panel-grid panel-has-style\" ><div style=\"padding: 2em 0; \" data-overlay=\"true\" class=\"panel-row-style panel-row-style-for-790-9\" ><div id=\"pgc-790-9-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-9-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"11\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-9-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p class=\"p1\">W\u00e4hrend es schwierig bleibt, Original Play zu definieren, kann der Erfahrungsprozess aufgezeigt und durch einen Mentor begleitet werden. Wer spielen zu lernen sucht, ben\u00f6tigt eine Umgebung, die Sanftmut, Mitgef\u00fchl und Freundlichkeit in Gedanken, Geist und Tun f\u00f6rdert. Dies ist die \u00d6kologie eines Spielplatzes, wie er von Kindern geschaffen wird.<\/p>\n<p class=\"p1\">Was folgt, ist der erste Schritt in einer Lehrzeit in Original Play. Original Play ist eine lange und zeitweise anspruchsvolle geistig-k\u00f6rperliche und spirituelle Disziplin. Jede Person kann unterschiedlich spielen, w\u00e4hrend die gleichen Prinzipien angewandt werden. Wenn wir wieder zu spielen beginnen, nachdem wir Jahre davon entfernt waren, bringen wir einen anderen Hintergrund und neue Gewohnheiten mit. Aus diesem Grund h\u00e4ngt die L\u00e4nge dieser Lehrzeit vom Einzelnen ab. Bei genauer Betrachtung bist du alleine f\u00fcr deine eigene Entwicklung in Original Play verantwortlich. Es gibt keine festgelegte Dauer f\u00fcr eine Lehrzeit in Original Play. Meine Lehrzeit dauerte beispielsweise \u00fcber 25 Jahre.<\/p>\n<p class=\"p1\">Wer eine Lehrzeit in Original Play anstrebt, muss in der Lage sein, \u00fcber die gewohnten Kategorien hinaus zu denken und die Herzen derer zu ber\u00fchren, mit denen man spielt. Es gibt keinen leichten Weg, dies zu erkennen. Original Play kann nicht unterrichtet, nur durch Erfahrung erlernt werden. Durch das Spielen bekommst du eine direkte Erfahrung aus erster Hand \u00fcber das andere Lebewesen. Du musst die Tatsache respektieren lernen, dass du in diesem Geben und Nehmen deinen Mentor findest. Du wirst deine St\u00e4rken und Schw\u00e4chen sp\u00fcren. Du wirst mit deinem Geist spielen lernen, nicht mit deinem Ego.<\/p>\n<p class=\"p1\">Was folgt, sind Richtlinien f\u00fcr eine Basis in Original Play. Es ist wichtig darauf hinzuweisen, dass Original Play von Meistern gelernt wird - Kindern. Man lernt Original Play weder von Erwachsenen, noch dadurch, dass man an Workshops teilnimmt. Workshops sind Einf\u00fchrungen und konzipiert als etwas, das ich 'Zug\u00e4nglichkeitstraining' nenne. Das ist ein Training, das dich darauf vorbereitet, deinen Mentor in Kindern zu finden. Nur so werden deine Erfahrung, \u00dcbung und Zeit dein Mitgef\u00fchl ausweiten, w\u00e4hrend du in deinem Alltag spielst.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-10\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-10\" style=\"padding: 1em 0; \" data-stretch-type=\"full-stretched\" data-overlay=\"true\" ><div id=\"pgc-790-10-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-10-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"12\" ><div class=\"so-parallax panel-widget-style panel-widget-style-for-790-10-0-0\" style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" ><img width=\"1200\" height=\"600\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06.jpg\" class=\"attachment-full size-full\" alt=\"Foto: zwei H\u00e4nder ber\u00fchren sich sanft\" decoding=\"async\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06.jpg 1200w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-300x150.jpg 300w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-768x384.jpg 768w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-1024x512.jpg 1024w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-600x300.jpg 600w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-480x240.jpg 480w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-830x415.jpg 830w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-230x115.jpg 230w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/bildung-06-350x175.jpg 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">\"Wer eine Lehrzeit in Original Play anstrebt,<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">muss in der Lage sein,<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\"> \u00fcber die gewohnten Kategorien hinaus zu denken<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\"> und die Herzen derer zu ber\u00fchren,<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\"> mit denen man spielt.\"<\/span><\/h2>\n<h6 style=\"text-align: center;\"><span style=\"color: #fff;\">Fred Donaldson<\/span><\/h6>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-11\"  class=\"panel-grid panel-has-style\" ><div style=\"padding: 2em 0; \" data-overlay=\"true\" class=\"panel-row-style panel-row-style-for-790-11\" ><div id=\"pgc-790-11-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-11-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"13\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-11-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #c62a2c;\">Grundriss einer Lehrzeit in Original Play<\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Hier folgen die grundlegenden Umrisse einer Lehrzeit in Original Play. Die benannten Elemente sind alles andere als vollst\u00e4ndig. Sie sollen denen, die bereits spielen, als Referenz dienen oder Hinweise geben, welche Richtung sie weiter verfolgen sollten. Die angegebenen Zahlen stellen ein Minimum dar. Bei Erf\u00fcllung der folgenden Kriterien ist es m\u00f6glich als \u201erecommended apprentice\u201c zertifiziert zu werden.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Die Lehrzeit besteht aus einem Minimum von:<\/span><\/p>\n<ul>\n<li class=\"p1\"><span class=\"s1\">3 Jahren regelm\u00e4\u00dfigem Spiel mit Kindern und Jugendlichen<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">100 Spielstunden mit Kindern pro Jahr = 300 Stunden Spiel mit Kindern insgesamt<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">2 Trainingsseminaren zur Einf\u00fchrung (\u201eBasic Training Seminar\u201c)<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">2 vertiefenden Trainingsseminaren (\u201eAdvanced Training Seminar\u201c)<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">3 Spielsitzungen mit Kindern unterschiedlicher Art under der individuellen Supervision von Jolanta Graczykowska<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Von den 300 Stunden Spiel entfallen mindestens 100 Stunden auf das Spiel mit Kindern mit besonderen Bed\u00fcrfnissen.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Mindestanzahl von Kindern, mit denen in 3 Jahren gespielt wurde: 3000. Diese beinhalten Kinder in verschiedenen Kinderg\u00e4rten und Schulen (\u00f6ffentliche, private, integrative, besondere Kinderg\u00e4rten) und verschiedene Arten von Schulen (Grundschule, Gymnasium, weiterf\u00fchrende Schule), Kinderheime und Waisenh\u00e4user<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Die 300 Spielstunden m\u00fcssen von den teilnehmenden Einrichtungen best\u00e4tigt werden<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">F\u00fcr die Teilnahme an einem Training Seminar darf der letzte besuchte Workshop nicht l\u00e4nger als ein Jahr zur\u00fcck liegen, ansonsten muss der Einf\u00fchrungsworkshop erst wiederholt werden.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Nur Lehrlinge, die alle Anforderungen an die Lehrzeit erf\u00fcllt haben und zertifiziert sind, k\u00f6nnen auf der offiziellen Original Play Website (www.originalplay.eu) als \u201erecommended apprentice\u201c aufgef\u00fchrt werden.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">\u201eRecommended apprentices\u201c m\u00fcssen, um ihren Status als \u201erecommended apprentice\u201c zu behalten, weiterhin mit Kindern spielen und Workshops, individuelles Training oder Supervision wenigstens einmal im Jahr wahrnehmen.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Ein Lehrzeit-Zertifikat ist eine Best\u00e4tigung, nicht f\u00fcr ein Ende, sondern einen Anfang.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Es ist der Nachweis f\u00fcr die moralische Verantwortung und Verpflichtung gegen\u00fcber der Disziplin, der Weisheit und dem Mitgef\u00fchl von Original Play.<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\">Jolanta Graczykowska MA and O. Fred Donaldson Ph.D. sind die einzigen ausgewiesenen Mentoren im Original Play. Sie vergeben Zertifikate f\u00fcr Workshops und Seminare als reine Teilnahmebescheinigungen. Zus\u00e4tzlich zu Teilnahmebescheinigungen stellt die \u201eInternationale Stiftung f\u00fcr Original Play\u201c Zertifikate aus, die eine abgeschlossene Lehrzeit im Original Play best\u00e4tigen.\u00a0<\/span><span class=\"s1\">Einzelpersonen, die auf der europ\u00e4ischen Website (www.originalplay.eu) als \u201erecommended apprentice\u201c aufgef\u00fchrt werden wollen, senden die folgenden Informationen zur Begutachtung an <a href=\"mailto:jola@originalplay.pl\">Jolanta Graczykowska<\/a>. Jede Person ist f\u00fcr die Richtigkeit der bereitgestellten Informationen verantwortlich und aktualisiert sie bei Bedarf.<\/span><\/p>\n<ul>\n<li class=\"p1\"><span class=\"s1\">Name, Adresse, Telefon, E-Mail<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Art und Datum der absolvierten Original Play Seminare und praktischen Trainings (keine Workshops)<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Jahre\/Stunden der Erfahrung im Original Play mit Kindern<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Art und Anzahl der Einrichtungen und Kinder, mit denen gespielt wurde<\/span><\/li>\n<\/ul>\n<p class=\"p1\">\n<\/div>\n<\/div><\/div><\/div><div id=\"panel-790-11-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"14\" ><div style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" class=\"panel-widget-style panel-widget-style-for-790-11-0-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #c62a2c;\">Sicherheitsrichtlinien f\u00fcr Original Play Spielleiter*innen<\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\"><b>Selbst<\/b><\/span><\/p>\n<ul>\n<li class=\"li2\"><span class=\"s1\">Stellen Sie sicher, dass Sie physisch und emotional spielbereit sind<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Kleiden Sie sich angemessen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Ergreifen geeigneter Ma\u00dfnahmen, die von der Einrichtung verlangt werden, z. B. Strafregisterbescheinigung vorlegen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Seien Sie offen f\u00fcr das Unerwartete<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\"><b>Umgebung<\/b><\/span><\/p>\n<ul>\n<li class=\"li2\"><span class=\"s1\">Bereiten Sie einen Brief an Mitarbeiter*innen und Eltern vor, um sich vorzustellen, zu beschreiben, was Sie tun und warum, und geben Sie Kontaktinformationen an<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Bieten Sie Mitarbeitern*innen und Eltern an, ein Einf\u00fchrungsgespr\u00e4ch zu halten und \/ oder sich mit ihnen zu treffen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Stellen Sie sicher, dass die Spielfl\u00e4che sicher ist<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Stellen Sie sicher, dass die Umgebung sicher und frei von Ablenkungen ist<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">\u201ePolitik der offenen T\u00fcr\u201c: Spielen Sie in offenen, beobachtbaren R\u00e4umen. T\u00fcren immer offen halten; seien Sie institutionellen Erwachsenen gegen\u00fcber klar, dass Ihr Spielraum \/ Ihre Spielzeit f\u00fcr sie immer einsehbar ist<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\"><b>Andere Erwachsene<\/b><\/span><\/p>\n<ul>\n<li class=\"li2\"><span class=\"s1\">Erlauben Sie nur Erwachsenen, sich am Spiel zu beteiligen, die Original Play trainiert haben oder denen Sie pers\u00f6nlich zustimmen (z.B. die P\u00e4dagog*innen der Kinder)<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Informieren Sie die anwesenden Erwachsenen, die Abl\u00e4ufe zu beobachten und was von ihnen erwartet wird<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Stellen Sie sicher, dass eine P\u00e4dagog*in \/ Betreuer*in im Raum ist<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\"><b>Kinder<\/b><\/span><\/p>\n<ul>\n<li class=\"li2\"><span class=\"s1\">Spielen Sie nur mit der Anzahl der Kinder, mit denen Sie sicher umgehen k\u00f6nnen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Spielen Sie nur mit Kindern, mit denen Sie sich sicher f\u00fchlen. Passen Sie Ihr Spiel an die Bed\u00fcrfnisse jedes Kindes an<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Verwenden Sie eine f\u00fcr jedes Kind geeignete Ber\u00fchrung; ber\u00fchren Sie, um die Bed\u00fcrfnisse des Kindes zu erf\u00fcllen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Bei Kindern in Rollst\u00fchlen m\u00fcssen Kinder und Erwachsene um Erlaubnis gebeten werden, bevor sie heraus genommen werden<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Seien Sie sich dar\u00fcber im Klaren, dass kein Kind teilnehmen muss und dass Zuschauen genauso in Ordnung ist<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Wenn Kinder ankommen, suchen Sie nach physischen Verletzungen oder Dingen wie Brillen, H\u00f6rger\u00e4ten oder Zahnspangen, die Sie vor dem Spielen ber\u00fccksichtigen m\u00fcssen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Wenn Sie Kinder zum Spielen ausw\u00e4hlen, z\u00f6gern Sie nicht zu lange, um ein Kind, das nicht spielen m\u00f6chte, in Verlegenheit zu bringen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Laden Sie bei jeder Spielrunde auch diejenigen ein, die nicht spielen m\u00f6chten, damit sie sich nicht ausgeschlossen f\u00fchlen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Machen Sie sich die Abl\u00e4ufe klar, wie Sie das Spiel beenden werden<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Nehmen Sie sich am Ende des Spiels Zeit, um mit den Kindern zu sprechen<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Stellen Sie w\u00e4hrend des Spiels angemessene Aktions- und Ruhezeiten zur Verf\u00fcgung<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Seien Sie sich dar\u00fcber im Klaren, dass Sicherheit Ihr erstes Anliegen ist. Wenn Sie aus irgendeinem Grund feststellen, dass das Spiel nicht sicher ist, beenden Sie das Spiel<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Beobachten Sie Kinder, die nicht spielen, um die Sicherheit in der gesamten Gruppe zu gew\u00e4hrleisten<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Leiten Sie unsicheres emotionales und \/ oder physisches Verhalten von Kindern auf Sie um<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Sollte es zu einem Unfall kommen, beenden Sie das Spiel und kl\u00e4ren Sie, ob physische oder emotionale Erste Hilfe erforderlich ist<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Verwenden Sie nach dem Spielen eine \u00dcbergangsber\u00fchrung, die f\u00fcr jedes Kind angemessen ist<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Planen Sie eine den Kindern angemessene Spielzeit ein<\/span><\/li>\n<li class=\"li2\"><span class=\"s1\">Achten Sie darauf, dass die Kinder zum Spielen angemessen gekleidet sind, z. B. entfernen Sie die Halst\u00fccher, Armbanduhren, gro\u00dfe Ohrringe<\/span><\/li>\n<\/ul>\n<h2><a href=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2019\/11\/Sicherheitsrichtlinien-1.pdf\">Download Original Play Sicherheitsrichtlinien als pdf\u00a0<\/a><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-790-12\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-790-12\" style=\"padding: 0em 0; \" data-stretch-type=\"full-stretched\" data-overlay=\"true\" ><div id=\"pgc-790-12-0\"  class=\"panel-grid-cell\" ><div id=\"panel-790-12-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"15\" ><div class=\"so-parallax panel-widget-style panel-widget-style-for-790-12-0-0\" style=\"text-align: left;\" data-title-color=\"#443f3f\" data-headings-color=\"#443f3f\" ><img width=\"1200\" height=\"600\" src=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"eager\" data-siteorigin-parallax=\"true\" srcset=\"https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices.jpg 1200w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-300x150.jpg 300w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-768x384.jpg 768w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-1024x512.jpg 1024w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-600x300.jpg 600w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-480x240.jpg 480w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-830x415.jpg 830w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-230x115.jpg 230w, https:\/\/www.hiersein.at\/op\/wp-content\/uploads\/2016\/02\/original-play-apprentices-350x175.jpg 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Gl\u00fcckliche Spielgef\u00e4hrt*innen nach dem Spielen beim Willkommensfest f\u00fcr Fl\u00fcchtlinge in Meidling, 2015<\/span><\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><input class=\"fooboxshare_post_id\" type=\"hidden\" value=\"790\"\/>","protected":false},"excerpt":{"rendered":"<p>Weiterbildungen\u00a0mit Fred Donaldson und Jolanta Graczykowska<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page_front-page.php","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"_links":{"self":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/pages\/790"}],"collection":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/comments?post=790"}],"version-history":[{"count":95,"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/pages\/790\/revisions"}],"predecessor-version":[{"id":6206,"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/pages\/790\/revisions\/6206"}],"wp:attachment":[{"href":"https:\/\/www.hiersein.at\/op\/wp-json\/wp\/v2\/media?parent=790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}